{"id":3159,"date":"2019-02-28T13:52:37","date_gmt":"2019-02-28T13:52:37","guid":{"rendered":"https:\/\/www.melchioni.com\/2022\/02\/28\/melchioni-pronto\/"},"modified":"2022-03-31T14:12:30","modified_gmt":"2022-03-31T14:12:30","slug":"melchioni-pronto","status":"publish","type":"post","link":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/","title":{"rendered":"Melchioni Ready"},"content":{"rendered":"<p style=\"text-align: left;\">Nasce Melchioni Ready, il nuovo e-commerce di elettronica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nasce Melchioni Ready, il nuovo e-commerce di elettronica.<\/p>\n","protected":false},"author":1,"featured_media":3102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[108],"class_list":["post-3159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storia-aziendale-it","tag-storia-it-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melchioni Ready - Melchioni Group SpA<\/title>\n<meta name=\"description\" content=\"Mario Melchioni, fondatore della Melchioni srl, da il via ad un progetto che ancora oggi conquista il mercato.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melchioni Ready - Melchioni Group SpA\" \/>\n<meta property=\"og:description\" content=\"Mario Melchioni, fondatore della Melchioni srl, da il via ad un progetto che ancora oggi conquista il mercato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/\" \/>\n<meta property=\"og:site_name\" content=\"Melchioni Group SpA\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-28T13:52:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-31T14:12:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/01\/Logo_Ready.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"paolo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"paolo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/\"},\"author\":{\"name\":\"paolo\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#\\\/schema\\\/person\\\/e5e9e8efc4408c3c825b24403dd70563\"},\"headline\":\"Melchioni Ready\",\"datePublished\":\"2019-02-28T13:52:37+00:00\",\"dateModified\":\"2022-03-31T14:12:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.melchioni.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo_Ready.jpg\",\"keywords\":[\"storia\"],\"articleSection\":[\"Storia Aziendale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/\",\"url\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/\",\"name\":\"Melchioni Ready - Melchioni Group SpA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.melchioni.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo_Ready.jpg\",\"datePublished\":\"2019-02-28T13:52:37+00:00\",\"dateModified\":\"2022-03-31T14:12:30+00:00\",\"description\":\"Mario Melchioni, fondatore della Melchioni srl, da il via ad un progetto che ancora oggi conquista il mercato.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/melchioni-pronto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.melchioni.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo_Ready.jpg\",\"contentUrl\":\"https:\\\/\\\/www.melchioni.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo_Ready.jpg\",\"width\":150,\"height\":150},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/\",\"name\":\"Melchioni Group SpA\",\"description\":\"70 years of experience and innovation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#organization\",\"name\":\"Melchioni S.p.A.\",\"url\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.melchioni.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Melchioni.jpg\",\"contentUrl\":\"https:\\\/\\\/www.melchioni.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Logo_Melchioni.jpg\",\"width\":150,\"height\":150,\"caption\":\"Melchioni S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.melchioni.com\\\/it\\\/#\\\/schema\\\/person\\\/e5e9e8efc4408c3c825b24403dd70563\",\"name\":\"paolo\",\"sameAs\":[\"https:\\\/\\\/www.melchioni.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melchioni Ready - Melchioni Group SpA","description":"Mario Melchioni, fondatore della Melchioni srl, da il via ad un progetto che ancora oggi conquista il mercato.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Melchioni Ready - Melchioni Group SpA","og_description":"Mario Melchioni, fondatore della Melchioni srl, da il via ad un progetto che ancora oggi conquista il mercato.","og_url":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/","og_site_name":"Melchioni Group SpA","article_published_time":"2019-02-28T13:52:37+00:00","article_modified_time":"2022-03-31T14:12:30+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/01\/Logo_Ready.jpg","type":"image\/jpeg"}],"author":"paolo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"paolo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/#article","isPartOf":{"@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/"},"author":{"name":"paolo","@id":"https:\/\/www.melchioni.com\/it\/#\/schema\/person\/e5e9e8efc4408c3c825b24403dd70563"},"headline":"Melchioni Ready","datePublished":"2019-02-28T13:52:37+00:00","dateModified":"2022-03-31T14:12:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/"},"wordCount":10,"publisher":{"@id":"https:\/\/www.melchioni.com\/it\/#organization"},"image":{"@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/01\/Logo_Ready.jpg","keywords":["storia"],"articleSection":["Storia Aziendale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/","url":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/","name":"Melchioni Ready - Melchioni Group SpA","isPartOf":{"@id":"https:\/\/www.melchioni.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/#primaryimage"},"image":{"@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/01\/Logo_Ready.jpg","datePublished":"2019-02-28T13:52:37+00:00","dateModified":"2022-03-31T14:12:30+00:00","description":"Mario Melchioni, fondatore della Melchioni srl, da il via ad un progetto che ancora oggi conquista il mercato.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.melchioni.com\/it\/melchioni-pronto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.melchioni.com\/it\/melchioni-pronto\/#primaryimage","url":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/01\/Logo_Ready.jpg","contentUrl":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/01\/Logo_Ready.jpg","width":150,"height":150},{"@type":"WebSite","@id":"https:\/\/www.melchioni.com\/it\/#website","url":"https:\/\/www.melchioni.com\/it\/","name":"Melchioni Group SpA","description":"70 years of experience and innovation","publisher":{"@id":"https:\/\/www.melchioni.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.melchioni.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.melchioni.com\/it\/#organization","name":"Melchioni S.p.A.","url":"https:\/\/www.melchioni.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.melchioni.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/12\/Logo_Melchioni.jpg","contentUrl":"https:\/\/www.melchioni.com\/wp-content\/uploads\/2019\/12\/Logo_Melchioni.jpg","width":150,"height":150,"caption":"Melchioni S.p.A."},"image":{"@id":"https:\/\/www.melchioni.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.melchioni.com\/it\/#\/schema\/person\/e5e9e8efc4408c3c825b24403dd70563","name":"paolo","sameAs":["https:\/\/www.melchioni.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/posts\/3159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/comments?post=3159"}],"version-history":[{"count":2,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/posts\/3159\/revisions"}],"predecessor-version":[{"id":3348,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/posts\/3159\/revisions\/3348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/media\/3102"}],"wp:attachment":[{"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/media?parent=3159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/categories?post=3159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.melchioni.com\/it\/wp-json\/wp\/v2\/tags?post=3159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}